{"id":19309,"date":"2024-04-23T15:37:58","date_gmt":"2024-04-23T13:37:58","guid":{"rendered":"https:\/\/daisec.de\/?post_type=tribe_events&#038;p=19309"},"modified":"2024-04-25T12:18:43","modified_gmt":"2024-04-25T10:18:43","slug":"deep-dive-into-deep-learning-07-06-2024","status":"publish","type":"tribe_events","link":"https:\/\/daisec.de\/en\/event\/deep-dive-into-deep-learning-07-06-2024\/","title":{"rendered":"Deep Dive into Deep Learning \u2013 KI verstehen und anwenden"},"content":{"rendered":"\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:80%\"><div  class=\"tribe-events-schedule tribe-clearfix bold\" >\n\t<p class=\"tribe-events-schedule__datetime\">\n\t\t<span class=\"tribe-events-schedule__date tribe-events-schedule__date--start\">\n\t\t\t07.06.2024\t\t<\/span>\n\n\t\t\t\t\t<span class=\"tribe-events-schedule__separator tribe-events-schedule__separator--date\">\n\t\t\t\t| \t\t\t<\/span>\n\t\t\t<span class=\"tribe-events-schedule__time tribe-events-schedule__time--start\">\n\t\t\t\t9:15\t\t\t<\/span>\n\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"tribe-events-schedule__separator tribe-events-schedule__separator--time\">\n\t\t\t\t\t &#8211; \t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"tribe-events-schedule__time tribe-events-schedule__time--end\">\n\t\t\t\t\t15:00\t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:15%\"><div  class=\"tribe-block tribe-block__event-price\" >\n\t\t\t<span class=\"tribe-block__event-price__cost\"> Free <\/span>\n\t\t<\/div>\n<\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"230\" data-src=\"https:\/\/daisec.de\/wp-content\/uploads\/2023\/09\/Banner-Bootcamps-1024x230.png\" alt=\"\" class=\"wp-image-14966 lazyload\" data-srcset=\"https:\/\/daisec.de\/wp-content\/uploads\/2023\/09\/Banner-Bootcamps-1024x230.png 1024w, https:\/\/daisec.de\/wp-content\/uploads\/2023\/09\/Banner-Bootcamps-300x68.png 300w, https:\/\/daisec.de\/wp-content\/uploads\/2023\/09\/Banner-Bootcamps-768x173.png 768w, https:\/\/daisec.de\/wp-content\/uploads\/2023\/09\/Banner-Bootcamps-1536x346.png 1536w, https:\/\/daisec.de\/wp-content\/uploads\/2023\/09\/Banner-Bootcamps-18x4.png 18w, https:\/\/daisec.de\/wp-content\/uploads\/2023\/09\/Banner-Bootcamps.png 2000w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/230;\" \/><\/figure>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-94bc23d7 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:75%\">\n<p><strong>K\u00fcnstliche Intelligenz ist aus unserem Alltag nicht mehr wegzudenken. Angefangen bei der automatischen Erkennung von Verkehrsschildern, beim Autofahren, \u00fcber das Einschalten von Ger\u00e4ten mittels Sprachsteuerung, bis hin zum Entsperren unserer Smartphones mit Gesichtserkennung &#8211; KI hat sich fest in unserem Leben etabliert. Auch in der Automobilindustrie und besonders im Kontext des autonomen Fahrens werden KI-Algorithmen zunehmend bedeutsam. <\/strong><\/p>\n\n\n\n<p><strong>Doch wie ist es \u00fcberhaupt m\u00f6glich, einer leblosen Maschine solche F\u00e4higkeiten beizubringen? Mit den klassischen Programmierparadigmen wie if-then-else-Anweisungen oder Schleifen st\u00f6\u00dft man dabei schnell an Grenzen. Hier kommen KI-Algorithmen ins Spiel.<\/strong><\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\" style=\"font-style:normal;font-weight:800\">Unser Angebot<\/h4>\n\n\n\n<p>In einem intensiven Theorie-Modul erlangen Sie grundlegende Kenntnisse im Bereich der neuronalen Netze und insbesondere des Deep Learning kennen. In mehreren Praxis-Modulen lernen Sie, Ihr Wissen anzuwenden und programmieren eigenst\u00e4ndig erste KI-Anwendungen.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\" style=\"font-style:normal;font-weight:800\">Lerninhalte<\/h4>\n\n\n\n<p>Enthalten in unserem Bottcamp sind:<\/p>\n\n\n\n<p>\u2022 <strong>Theorie-Modul<\/strong> (vor Ort, ein Tag): bestehend aus 3 x ca. 1 h Einheiten zum Thema KI<br><br>\u2022 <strong>Praxis-Modul 1:<\/strong> Interaktive Einf\u00fchrung in die Grundlagen von Python mit Jupyter-Notebooks, Grundlagen der Datenverarbeitung, -aufbereitung und -visualisierung<br><br>\u2022 <strong>Praxis-Modul 2:<\/strong> Nutzung von Single-Layer-Machine-Learning-Modellen zur L\u00f6sung eines Zwei-Klassen-Problems: Support-Vector-Maschinen vs. Neuronales Netz. Aufteilung und Nutzung von Datens\u00e4tzen, Anwendung passender Metriken zur Evaluierung, Nutzung von High-Level Machine-Learning-Bibliotheken wie SciKit-Learn<br><br>\u2022 <strong>Praxis-Modul 3:<\/strong> Nutzung von tiefen neuronalen Netzwerken zur L\u00f6sung eines Vielklassen-Klassifizierungs-Problems, Kennenlernen von anerkannten akademischen Datens\u00e4tzen wie MNIST und CIFAR-10, Einf\u00fchrung in die Nutzung der Deep-Learning-Bibliotheken PyTorch und Tensorflow, Nutzung und Anpassung von vortrainierten Modellen<br><br>\u2022 <strong>Praxis-Modul 4:<\/strong> Nutzung von Faltungsnetzwerken zur L\u00f6sung von anspruchsvolleren Bildverarbeitungs-Problemen wie der semantischen Segmentierung und der Tiefensch\u00e4tzung von Verkehrsszenarien, Nutzung von Regularisierungsmethoden im Training<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\" style=\"font-style:normal;font-weight:800\">Ihr Vorteil<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Sie lernen grundlegende Methoden des Maschinellen Lernens und verstehen deren Funktionsweise<\/li>\n\n\n\n<li>Sie lernen verschiedene Anwendungsbeispiele von Neuronalen Netzen kennen<\/li>\n\n\n\n<li>Programmierkenntnisse in Python und lernen High-Level-Machine-Learning-Bibliotheken: SciKit-Learn, PyTorch und Tensorflow<\/li>\n\n\n\n<li>Sie lernen eigenst\u00e4ndig KI-Modelle zu trainieren und anzuwenden<\/li>\n\n\n\n<li>Sie lernen die bekanntesten Benchmark Datens\u00e4tze kennen und wissen, wie Sie diese nutzen k\u00f6nnen<\/li>\n\n\n\n<li>Sie lernen KI-Modelle zu evaluieren und zu vergleichen<\/li>\n\n\n\n<li>Sie lernen verschiedene Netzwerkarchitekturen und Aufgabentypen kennen<\/li>\n<\/ul>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\" style=\"font-style:normal;font-weight:800\">Zielgruppe und Vorkenntnisse<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mathematische Kenntnisse im Bereich Vektoren\/Matrizen sowie weiterf\u00fchrende Programmiererfahrung sind f\u00fcr die Praxis Module notwendig<\/li>\n\n\n\n<li>Fach- und F\u00fchrungskr\u00e4fte aus den Bereichen Mobilit\u00e4t und Produktion<\/li>\n\n\n\n<li>Einsteiger im Bereich der Entwicklung von KI-Modellen<\/li>\n<\/ul>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\" style=\"font-style:normal;font-weight:800\">Organisatorisches<\/h4>\n\n\n\n<p>Das eint\u00e4gige Theoriemodul findet als Pr\u00e4senzveranstaltung in den R\u00e4umen <strong>VW 1 und 2<\/strong> des Nieders\u00e4chsischen Forschungszentrums f\u00fcr Fahrzeugtechnik statt und wird im Abstand von 2 Monaten in deutscher Sprache angeboten. Im Anschluss erhalten Sie Zugang zu unseren interaktiven Online-Schulungsmaterialien. Diese k\u00f6nnen Sie in den folgenden Wochen bis Monaten eigenst\u00e4ndig bearbeiten und erhalten in regelm\u00e4\u00dfigen Abst\u00e4nden Feedback zu Ihren L\u00f6sungen. Die Kursmaterialien sind ausschlie\u00dflich auf Englisch verf\u00fcgbar, wir stehen Ihnen aber selbstverst\u00e4ndlich f\u00fcr Fragen und Hilfestellungen zur Verf\u00fcgung. F\u00fcr die Bearbeitung der Lerneinheiten ben\u00f6tigen Sie lediglich einen Computer mit Internetzugang. Alle weiteren Informationen erhalten Sie vor Ort w\u00e4hrend des Theorietages.<\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\">\n<div class=\"wp-block-group event-rund-platz has-colibri-color-8-background-color has-background has-medium-font-size is-vertical is-content-justification-center is-layout-flex wp-container-core-group-is-layout-4b2eccd6 wp-block-group-is-layout-flex\">\n<h4 class=\"wp-block-heading has-text-align-center\" style=\"font-style:normal;font-weight:800\">Kontakt<\/h4>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer wp-container-content-728072c3\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-full is-resized is-style-rounded\"><img decoding=\"async\" width=\"1080\" height=\"1080\" data-src=\"https:\/\/daisec.de\/wp-content\/uploads\/2024\/02\/Bartels-Timo-1.png\" alt=\"\" class=\"wp-image-17383 lazyload\" style=\"--smush-placeholder-width: 1080px; --smush-placeholder-aspect-ratio: 1080\/1080;width:192px;height:192px\" data-srcset=\"https:\/\/daisec.de\/wp-content\/uploads\/2024\/02\/Bartels-Timo-1.png 1080w, https:\/\/daisec.de\/wp-content\/uploads\/2024\/02\/Bartels-Timo-1-300x300.png 300w, https:\/\/daisec.de\/wp-content\/uploads\/2024\/02\/Bartels-Timo-1-1024x1024.png 1024w, https:\/\/daisec.de\/wp-content\/uploads\/2024\/02\/Bartels-Timo-1-150x150.png 150w, https:\/\/daisec.de\/wp-content\/uploads\/2024\/02\/Bartels-Timo-1-768x768.png 768w, https:\/\/daisec.de\/wp-content\/uploads\/2024\/02\/Bartels-Timo-1-12x12.png 12w\" data-sizes=\"(max-width: 1080px) 100vw, 1080px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/figure>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer wp-container-content-728072c3\"><\/div>\n\n\n\n<h6 class=\"wp-block-heading has-text-align-center\">Timo Bartels<\/h6>\n\n\n\n<p class=\"has-text-align-center\" style=\"font-size:14px\">Experte f\u00fcr KI im Automotive-Bereich<\/p>\n\n\n\n<p class=\"has-text-align-center\" style=\"font-size:14px\"><a href=\"mailto:bartels@daisec.de\">bartels@daisec.de<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group full-width event-rund-platz2 has-colibri-color-8-background-color has-background is-vertical is-content-justification-center is-layout-flex wp-container-core-group-is-layout-4b2eccd6 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<h4 class=\"wp-block-heading has-text-align-center\" style=\"font-size:30px;font-style:normal;font-weight:800\">Anmeldung<\/h4>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n<\/div>\n\n\n\n\n\n<div style=\"height:0px\" aria-hidden=\"true\" class=\"wp-block-spacer wp-container-content-62aae154\"><\/div>\n\n\n\n<p class=\"has-text-align-center\" style=\"font-size:12px\">Die Teilnehmerzahl ist auf 30 begrenzt.<br>Die Anmeldung schlie\u00dft drei Tage vor dem Veranstaltungstermin.<br>Sollten Sie Fragen oder Probleme mit der Anmeldung haben,<br>wenden Sie sich bitte an den oben angegebenen Kontakt.<\/p>\n<\/div>\n\n\n\n<div style=\"height:80px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\" style=\"font-size:30px;font-style:normal;font-weight:800\">Veranstaltungsort<\/h4>\n\n\n\n<div class=\"wp-block-group full-width is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-94bc23d7 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"500\" height=\"500\" data-src=\"https:\/\/daisec.de\/wp-content\/uploads\/2023\/08\/DAISEC-Event-Location-Icon-Image.gif\" alt=\"\" class=\"wp-image-14435 lazyload\" style=\"--smush-placeholder-width: 500px; --smush-placeholder-aspect-ratio: 500\/500;object-fit:cover;width:250px;height:250px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-content-justification-center is-layout-flex wp-container-core-group-is-layout-4b2eccd6 wp-block-group-is-layout-flex\"><div  class=\"tribe-block tribe-block__venue tribe-clearfix\" >\n\t\n\t\n<div class=\"tribe-block__venue__meta\">\n\t<div class=\"tribe-block__venue__name\">\n\t\t<h3><a href=\"https:\/\/daisec.de\/en\/venue\/\" title=\"Nieders\u00e4chsisches Forschungszentrum f\u00fcr Fahrzeugtechnik\">Nieders\u00e4chsisches Forschungszentrum f\u00fcr Fahrzeugtechnik<\/a><\/h3>\n\t<\/div>\n\n\t\n\t\t\t\t\t\t<address class=\"tribe-block__venue__address\">\n\t\t\t\t<span class=\"tribe-address\">\n\n<span class=\"tribe-street-address\">Hermann-Blenk-Stra\u00dfe 42<\/span>\n\t\n\t\t<br>\n\t\t<span class=\"tribe-locality\">Braunschweig<\/span><span class=\"tribe-delimiter\">,<\/span>\n\n\n\t<span class=\"tribe-postal-code\">38108<\/span>\n\n\t<span class=\"tribe-country-name\">Deutschland<\/span>\n\n<\/span>\n\n\t\t\t\t\t\t\t\t\t<a class=\"tribe-events-gmap\" href=\"https:\/\/maps.google.com\/maps?f=q&#038;source=s_q&#038;hl=en&#038;geocode=&#038;q=Hermann-Blenk-Stra%C3%9Fe+42+Braunschweig+38108+Deutschland\" title=\"Click to view a Google Map\" target=\"_blank\" rel=\"noreferrer noopener\">+ Google Map<\/a>\t\t\t\t\t\t\t<\/address>\n\t\t\n\t\t\n\t\t\t\t\t<span class=\"tribe-block__venue__website\"><a href=\"https:\/\/www.tu-braunschweig.de\/nff\" target=\"_self\" rel=\"external noopener\">View Venue Website<\/a><\/span><br \/>\n\t\t\t\n\t<\/div>\n\t\n\t<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-colibri-color-1-color has-alpha-channel-opacity has-colibri-color-1-background-color has-background is-style-wide\"\/>\n\n\n\n<div  class=\"tribe-compatibility-container\" >\n\t<div\n\t\t class=\"tribe-common tribe-events tribe-events-view tribe-events-view--widget-events-list tribe-events-widget\" \t\tdata-js=\"tribe-events-view\"\n\t\tdata-view-rest-url=\"https:\/\/daisec.de\/en\/wp-json\/tribe\/views\/v2\/html\"\n\t\tdata-view-manage-url=\"1\"\n\t\t\t\t\t\t\tdata-view-breakpoint-pointer=\"bccdcc5c-a3e7-470b-b6b8-4d26fb48833a\"\n\t\t\t>\n\t\t<div class=\"tribe-events-widget-events-list\">\n\n\t\t\t<script type=\"application\/ld+json\">\r\n[{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Cloudbetrieb und alternative Modelle: Abh\\u00e4ngigkeiten erkennen \\u2013 Alternativen gestalten\",\"description\":\"&lt;p&gt;Erfahren Sie, wie Sie kritische Anwendungen identifizieren, gef\\u00e4hrliche Abh\\u00e4ngigkeiten im IT-Betrieb sichtbar machen und mit alternativen Modellen mehr Kontrolle, Sicherheit und Zukunftsf\\u00e4higkeit gewinnen. Ziel der Veranstaltung ist es, Transparenz \\u00fcber die bestehenden Anwendungen einer Organisation zu schaffen, kritische Anwendungen systematisch zu identifizieren, deren Risiken und Abh\\u00e4ngigkeiten zu bewerten und den Grad der digitalen Souver\\u00e4nit\\u00e4t im IT-Betrieb einzusch\\u00e4tzen.&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/daisec.de\/wp-content\/uploads\/2026\/05\/Bild_2026-05-12_152630092.png\",\"url\":\"https:\/\/digitalzentrum-lmo.de\/veranstaltung\/cloud-abhaengigkeiten-alternativen\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-05-28T14:00:00+02:00\",\"endDate\":\"2026-05-28T17:00:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"Mittelstand-Digital Zentrum Lingen.M\\u00fcnster.Osnabr\\u00fcck\",\"description\":\"\",\"url\":\"https:\/\/daisec.de\/en\/venue\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Hauptstra\\u00dfe 25\",\"addressLocality\":\"Nordhorn\",\"postalCode\":\"48529\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"Mittelstand-Digital Zentrum Lingen.M\\u00fcnster.Osnabr\\u00fcck\",\"description\":\"\",\"url\":\"https:\/\/digitalzentrum-lmo.de\/\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"https:\/\/digitalzentrum-lmo.de\/\"},\"offers\":{\"@type\":\"Offer\",\"price\":\"0\",\"priceCurrency\":\"EUR\",\"url\":\"https:\/\/digitalzentrum-lmo.de\/veranstaltung\/cloud-abhaengigkeiten-alternativen\/\",\"category\":\"primary\",\"availability\":\"inStock\",\"validFrom\":\"2026-05-12T00:00:00+00:00\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Qualifizierungsprogramm Digitalisierungsmanager: KI &amp; Cybersicherheit\",\"description\":\"&lt;p&gt;In diesem Qualifizierungsprogramm erweitern und vertiefen Sie Ihr Wissen in K\\u00fcnstlicher Intelligenz (KI) und Cybersicherheit. Sie erhalten praxisnahe Einblicke in KI-Anwendungen, Prozessoptimierung und rechtliche Rahmenbedingungen und sammeln wertvolle Erfahrungen im Umgang mit digitalen Tools. So lernen Sie, digitale L\\u00f6sungen sicher und effektiv in Ihrem Unternehmen einzusetzen.&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/daisec.de\/wp-content\/uploads\/2025\/12\/2026-06-DAISEC-Qualifizierungsprogramm-Digitalisierungsmanager-KI-Cybersicherheit.png\",\"url\":\"https:\/\/daisec.de\/en\/event\/qualifizierungsprogramm-digitalisierungsmanager-ki-cybersicherheit-06-2026\/\",\"offers\":[{\"@type\":\"Offer\",\"url\":\"https:\/\/daisec.de\/en\/event\/qualifizierungsprogramm-digitalisierungsmanager-ki-cybersicherheit-06-2026\/\",\"price\":\"0\",\"category\":\"primary\",\"availability\":\"InStock\",\"priceCurrency\":\"USD\",\"validFrom\":\"2025-12-16T00:00:00+00:00\",\"validThrough\":\"2026-06-04T00:00:00+00:00\"}],\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-06-04T10:00:00+02:00\",\"endDate\":\"2026-06-04T15:00:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"Online\",\"description\":\"\",\"url\":\"https:\/\/daisec.de\/en\/venue\/\",\"address\":{\"@type\":\"PostalAddress\"},\"telephone\":\"\",\"sameAs\":\"\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Innovationskraft im Netzwerk: Von der Vision zum konkreten Handlungsplan\",\"description\":\"&lt;p&gt;In einer sich dynamisch ver\\u00e4ndernden Wirtschaftswelt ist Innovationskraft kein Zufallsprodukt, sondern das Ergebnis einer gezielten Gestaltung von Kultur, Strategie und methodischem Handeln. Dieser Workshop bietet Akteuren aus Wirtschaftsf\\u00f6rderung, Wissenschaft und Transfer eine praxisnahe Plattform, um die Innovationsf\\u00e4higkeit in ihren Institutionen und f\\u00fcr die KMU der Region nachhaltig zu st\\u00e4rken.&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/daisec.de\/wp-content\/uploads\/2026\/03\/event_139b1c8f-fca8-4747-9e0e-09a4704ff3b5.png\",\"url\":\"https:\/\/innomatch.nds.de\/events\/default\/innovationskraft-im-netzwerk-von-der-vision-zum-konkreten-handlungsplan\/zw2dJGpr0M\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-06-16T10:00:00+02:00\",\"endDate\":\"2026-06-16T15:30:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"Niedersachsen.next\",\"description\":\"\",\"url\":\"https:\/\/daisec.de\/en\/venue\/niedersachsen-next-schiffgraben-22-28-30175-hannover\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Schiffgraben 22-28\",\"addressLocality\":\"Hannover\",\"postalCode\":\"30175\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"Juliane Tholen, it.emsland\",\"description\":\"\",\"url\":\"\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"\"},\"performer\":\"Organization\"}]\r\n<\/script>\n\t\t\t<script data-js=\"tribe-events-view-data\" type=\"application\/json\">\n\t{\"slug\":\"widget-events-list\",\"prev_url\":\"\",\"next_url\":\"https:\\\/\\\/daisec.de\\\/en\\\/?post_type=tribe_events&eventDisplay=widget-events-list&paged=2\",\"view_class\":\"Tribe\\\\Events\\\\Views\\\\V2\\\\Views\\\\Widgets\\\\Widget_List_View\",\"view_slug\":\"widget-events-list\",\"view_label\":\"View\",\"view\":null,\"should_manage_url\":true,\"id\":null,\"alias-slugs\":null,\"title\":\"Events from 13.05. \\u2013 16.06. \\u2013 DAISEC\",\"limit\":\"3\",\"no_upcoming_events\":true,\"featured_events_only\":false,\"jsonld_enable\":true,\"tribe_is_list_widget\":false,\"admin_fields\":{\"title\":{\"label\":\"Title:\",\"type\":\"text\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-title\",\"name\":\"widget-tribe-widget-events-list[-1][title]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"limit\":{\"label\":\"Show:\",\"type\":\"number\",\"default\":5,\"min\":1,\"max\":10,\"step\":1,\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-limit\",\"name\":\"widget-tribe-widget-events-list[-1][limit]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"metadata_section\":{\"type\":\"fieldset\",\"classes\":\"tribe-common-form-control-checkbox-checkbox-group\",\"label\":\"Display:\",\"children\":{\"cost\":{\"type\":\"checkbox\",\"label\":\"Price\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-cost\",\"name\":\"widget-tribe-widget-events-list[-1][cost]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"venue\":{\"type\":\"checkbox\",\"label\":\"Venue\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-venue\",\"name\":\"widget-tribe-widget-events-list[-1][venue]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"street\":{\"type\":\"checkbox\",\"label\":\"Street\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-street\",\"name\":\"widget-tribe-widget-events-list[-1][street]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"city\":{\"type\":\"checkbox\",\"label\":\"City\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-city\",\"name\":\"widget-tribe-widget-events-list[-1][city]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"region\":{\"type\":\"checkbox\",\"label\":\"State (US) Or Province (Int)\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-region\",\"name\":\"widget-tribe-widget-events-list[-1][region]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"zip\":{\"type\":\"checkbox\",\"label\":\"Postal Code\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-zip\",\"name\":\"widget-tribe-widget-events-list[-1][zip]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"country\":{\"type\":\"checkbox\",\"label\":\"Country\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-country\",\"name\":\"widget-tribe-widget-events-list[-1][country]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"phone\":{\"type\":\"checkbox\",\"label\":\"Phone\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-phone\",\"name\":\"widget-tribe-widget-events-list[-1][phone]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"organizer\":{\"type\":\"checkbox\",\"label\":\"Organizer\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-organizer\",\"name\":\"widget-tribe-widget-events-list[-1][organizer]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"website\":{\"type\":\"checkbox\",\"label\":\"Website\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-website\",\"name\":\"widget-tribe-widget-events-list[-1][website]\",\"options\":[],\"placeholder\":\"\",\"value\":null}},\"parent_classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-metadata_section\",\"name\":\"widget-tribe-widget-events-list[-1][metadata_section]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"taxonomy_section\":{\"type\":\"section\",\"classes\":[\"calendar-widget-filters-container\"],\"label\":\"Filters:\",\"children\":{\"filters\":{\"type\":\"taxonomy-filters\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-filters\",\"label\":\"\",\"name\":\"widget-tribe-widget-events-list[-1][filters]\",\"options\":[],\"placeholder\":\"\",\"value\":null,\"list_items\":[]},\"operand\":{\"type\":\"fieldset\",\"classes\":\"tribe-common-form-control-checkbox-radio-group\",\"label\":\"Operand:\",\"selected\":\"OR\",\"children\":[{\"type\":\"radio\",\"label\":\"Match any\",\"button_value\":\"OR\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-operand\",\"name\":\"widget-tribe-widget-events-list[-1][operand]\",\"options\":[],\"placeholder\":\"\",\"value\":null},{\"type\":\"radio\",\"label\":\"Match all\",\"button_value\":\"AND\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-operand\",\"name\":\"widget-tribe-widget-events-list[-1][operand]\",\"options\":[],\"placeholder\":\"\",\"value\":null}],\"parent_classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-operand\",\"name\":\"widget-tribe-widget-events-list[-1][operand]\",\"options\":[],\"placeholder\":\"\",\"value\":null}},\"parent_classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-taxonomy_section\",\"name\":\"widget-tribe-widget-events-list[-1][taxonomy_section]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"taxonomy\":{\"type\":\"taxonomy\",\"classes\":\"calendar-widget-add-filter\",\"label\":\"Add a filter:\",\"placeholder\":\"Select a Taxonomy Term\",\"parent_classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-taxonomy\",\"name\":\"widget-tribe-widget-events-list[-1][taxonomy]\",\"options\":[],\"value\":null},\"no_upcoming_events\":{\"label\":\"Hide this widget if there are no upcoming events.\",\"type\":\"checkbox\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-no_upcoming_events\",\"name\":\"widget-tribe-widget-events-list[-1][no_upcoming_events]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"featured_events_only\":{\"label\":\"Limit to featured events only\",\"type\":\"checkbox\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-featured_events_only\",\"name\":\"widget-tribe-widget-events-list[-1][featured_events_only]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"jsonld_enable\":{\"label\":\"Generate JSON-LD data\",\"type\":\"checkbox\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list--1-jsonld_enable\",\"name\":\"widget-tribe-widget-events-list[-1][jsonld_enable]\",\"options\":[],\"placeholder\":\"\",\"value\":null}},\"venue\":false,\"country\":false,\"street\":false,\"city\":false,\"region\":false,\"zip\":false,\"phone\":false,\"cost\":false,\"organizer\":false,\"website\":false,\"operand\":\"OR\",\"filters\":[{\"filter_object\":{\"type\":\"multiselect\",\"name\":\"Kategorie\",\"slug\":\"filterbar_category\",\"priority\":1,\"values\":[{\"name\":\"Kurzvortrag \\\"Auf den Punkt\\\"\",\"depth\":0,\"value\":49,\"data\":{\"slug\":\"auf-den-punkt\"},\"class\":\"tribe-parent-cat tribe-events-category-auf-den-punkt\"},{\"name\":\"\\u00d6ffentliche Veranstaltung\",\"depth\":0,\"value\":30,\"data\":{\"slug\":\"public\"},\"class\":\"tribe-parent-cat tribe-events-category-public\"},{\"name\":\"Qualifizierungsprogramm\",\"depth\":0,\"value\":34,\"data\":{\"slug\":\"qualifizierungsprogramm\"},\"class\":\"tribe-parent-cat tribe-events-category-qualifizierungsprogramm parent-34 has-child closed\"},{\"name\":\"Digitalisierungsmanager\",\"depth\":1,\"value\":93,\"data\":{\"slug\":\"digitalisierungsmanager\"},\"class\":\"tribe-child-cat tribe-events-category-digitalisierungsmanager child-34\"},{\"name\":\"IT-Inforeihe\",\"depth\":1,\"value\":103,\"data\":{\"slug\":\"it-inforeihe\"},\"class\":\"tribe-child-cat tribe-events-category-it-inforeihe child-34\"},{\"name\":\"KI-Inforeihe\",\"depth\":1,\"value\":64,\"data\":{\"slug\":\"ki-inforeihe\"},\"class\":\"tribe-child-cat tribe-events-category-ki-inforeihe child-34\"},{\"name\":\"Webinar\",\"depth\":0,\"value\":32,\"data\":{\"slug\":\"webinar\"},\"class\":\"tribe-parent-cat tribe-events-category-webinar\"},{\"name\":\"Workshops\",\"depth\":0,\"value\":33,\"data\":{\"slug\":\"workshops\"},\"class\":\"tribe-parent-cat tribe-events-category-workshops\"}],\"free\":null,\"currentValue\":[],\"isActiveFilter\":true,\"queryArgs\":[],\"joinClause\":\"\",\"whereClause\":\"\",\"stack_managed\":false},\"label\":\"Kategorie\",\"selections_count\":\"\",\"selections\":\"\",\"toggle_id\":\"filterbar_category-toggle-bccdcc5c-a3e7-470b-b6b8-4d26fb48833a\",\"container_id\":\"filterbar_category-container-bccdcc5c-a3e7-470b-b6b8-4d26fb48833a\",\"pill_toggle_id\":\"filterbar_category-pill-toggle-bccdcc5c-a3e7-470b-b6b8-4d26fb48833a\",\"is_open\":false,\"name\":\"tribe_eventcategory[]\",\"fields\":[{\"type\":\"multiselect\",\"value\":\"\",\"id\":\"tribe-events-filterbar-f16a1469-filterbar_category\",\"name\":\"tribe_eventcategory[]\",\"options\":[{\"text\":\"Kurzvortrag \\\"Auf den Punkt\\\"\",\"id\":\"49\",\"value\":49},{\"text\":\"\\u00d6ffentliche Veranstaltung\",\"id\":\"30\",\"value\":30},{\"text\":\"Qualifizierungsprogramm\",\"id\":\"34\",\"value\":34},{\"text\":\"Digitalisierungsmanager\",\"id\":\"93\",\"value\":93},{\"text\":\"IT-Inforeihe\",\"id\":\"103\",\"value\":103},{\"text\":\"KI-Inforeihe\",\"id\":\"64\",\"value\":64},{\"text\":\"Webinar\",\"id\":\"32\",\"value\":32},{\"text\":\"Workshops\",\"id\":\"33\",\"value\":33}]}],\"type\":\"multiselect\"},{\"filter_object\":{\"type\":\"select\",\"name\":\"Serie\",\"slug\":\"filterbar_series_id\",\"priority\":2,\"values\":[{\"name\":\"3D-Druck Workshops\",\"value\":19583},{\"name\":\"Anwendungspotenzial von KI in der chinesischen Automobilindustrie und Transfer auf den globalen Markt\",\"value\":24099},{\"name\":\"Auf den Punkt gebracht\",\"value\":16722},{\"name\":\"Cybersicherheit f\\u00fcr Produktionsunternehmen\",\"value\":16818},{\"name\":\"Deep Dive into Deep Learning\",\"value\":16440},{\"name\":\"KI- und IT-Inforeihe\",\"value\":21360},{\"name\":\"KI-Inforeihe: Fachberatertagung e-masters\",\"value\":16407},{\"name\":\"KI-Inforeihe: Fachverband Metall NRW\",\"value\":16374},{\"name\":\"Meetup Cybersicherheit\",\"value\":14832}],\"free\":null,\"currentValue\":null,\"isActiveFilter\":true,\"queryArgs\":[],\"joinClause\":\"\",\"whereClause\":\"\",\"stack_managed\":false},\"label\":\"Serie\",\"selections_count\":\"\",\"selections\":\"\",\"toggle_id\":\"filterbar_series_id-toggle-bccdcc5c-a3e7-470b-b6b8-4d26fb48833a\",\"container_id\":\"filterbar_series_id-container-bccdcc5c-a3e7-470b-b6b8-4d26fb48833a\",\"pill_toggle_id\":\"filterbar_series_id-pill-toggle-bccdcc5c-a3e7-470b-b6b8-4d26fb48833a\",\"is_open\":false,\"name\":\"tribe_series_id[]\",\"fields\":[{\"type\":\"dropdown\",\"value\":null,\"id\":\"tribe-events-filterbar-0544cb5a-filterbar_series_id\",\"name\":\"tribe_series_id[]\",\"options\":[{\"text\":\"3D-Druck Workshops\",\"id\":\"19583\",\"value\":19583},{\"text\":\"Anwendungspotenzial von KI in der chinesischen Automobilindustrie und Transfer auf den globalen Markt\",\"id\":\"24099\",\"value\":24099},{\"text\":\"Auf den Punkt gebracht\",\"id\":\"16722\",\"value\":16722},{\"text\":\"Cybersicherheit f\\u00fcr Produktionsunternehmen\",\"id\":\"16818\",\"value\":16818},{\"text\":\"Deep Dive into Deep Learning\",\"id\":\"16440\",\"value\":16440},{\"text\":\"KI- und IT-Inforeihe\",\"id\":\"21360\",\"value\":21360},{\"text\":\"KI-Inforeihe: Fachberatertagung e-masters\",\"id\":\"16407\",\"value\":16407},{\"text\":\"KI-Inforeihe: Fachverband Metall NRW\",\"id\":\"16374\",\"value\":16374},{\"text\":\"Meetup Cybersicherheit\",\"id\":\"14832\",\"value\":14832}]}],\"type\":\"dropdown\"},{\"filter_object\":{\"type\":\"multiselect\",\"name\":\"Tags\",\"slug\":\"filterbar_tag\",\"priority\":3,\"values\":{\"67\":{\"name\":\"Cybersicherheit\",\"value\":67},\"188\":{\"name\":\"Forum\",\"value\":188},\"101\":{\"name\":\"innovation\",\"value\":101},\"36\":{\"name\":\"KI\",\"value\":36},\"157\":{\"name\":\"KMU\",\"value\":157},\"206\":{\"name\":\"Kultur\",\"value\":206},\"40\":{\"name\":\"Produktion\",\"value\":40},\"38\":{\"name\":\"Schulung\",\"value\":38},\"187\":{\"name\":\"Start-Ups\",\"value\":187},\"207\":{\"name\":\"Strategie\",\"value\":207},\"189\":{\"name\":\"Verwaltung\",\"value\":189},\"205\":{\"name\":\"Wirtschaft\",\"value\":205},\"166\":{\"name\":\"Wissenschaft\",\"value\":166},\"66\":{\"name\":\"Workshop\",\"value\":66}},\"free\":null,\"currentValue\":[],\"isActiveFilter\":true,\"queryArgs\":[],\"joinClause\":\"\",\"whereClause\":\"\",\"stack_managed\":false},\"label\":\"Tags\",\"selections_count\":\"\",\"selections\":\"\",\"toggle_id\":\"filterbar_tag-toggle-bccdcc5c-a3e7-470b-b6b8-4d26fb48833a\",\"container_id\":\"filterbar_tag-container-bccdcc5c-a3e7-470b-b6b8-4d26fb48833a\",\"pill_toggle_id\":\"filterbar_tag-pill-toggle-bccdcc5c-a3e7-470b-b6b8-4d26fb48833a\",\"is_open\":false,\"name\":\"tribe_tags[]\",\"fields\":[{\"type\":\"multiselect\",\"value\":\"\",\"id\":\"tribe-events-filterbar-34241f04-filterbar_tag\",\"name\":\"tribe_tags[]\",\"options\":[{\"text\":\"Cybersicherheit\",\"id\":\"67\",\"value\":67},{\"text\":\"Forum\",\"id\":\"188\",\"value\":188},{\"text\":\"innovation\",\"id\":\"101\",\"value\":101},{\"text\":\"KI\",\"id\":\"36\",\"value\":36},{\"text\":\"KMU\",\"id\":\"157\",\"value\":157},{\"text\":\"Kultur\",\"id\":\"206\",\"value\":206},{\"text\":\"Produktion\",\"id\":\"40\",\"value\":40},{\"text\":\"Schulung\",\"id\":\"38\",\"value\":38},{\"text\":\"Start-Ups\",\"id\":\"187\",\"value\":187},{\"text\":\"Strategie\",\"id\":\"207\",\"value\":207},{\"text\":\"Verwaltung\",\"id\":\"189\",\"value\":189},{\"text\":\"Wirtschaft\",\"id\":\"205\",\"value\":205},{\"text\":\"Wissenschaft\",\"id\":\"166\",\"value\":166},{\"text\":\"Workshop\",\"id\":\"66\",\"value\":66}]}],\"type\":\"multiselect\"},{\"filter_object\":{\"type\":\"checkbox\",\"name\":\"Wochentag\",\"slug\":\"filterbar_day_of_week\",\"priority\":4,\"values\":[{\"name\":\"Monday\",\"value\":2},{\"name\":\"Tuesday\",\"value\":3},{\"name\":\"Wednesday\",\"value\":4},{\"name\":\"Thursday\",\"value\":5},{\"name\":\"Friday\",\"value\":6},{\"name\":\"Saturday\",\"value\":7},{\"name\":\"Sunday\",\"value\":1}],\"free\":null,\"currentValue\":[],\"isActiveFilter\":true,\"queryArgs\":[],\"joinClause\":\"\",\"whereClause\":\"\",\"stack_managed\":false},\"label\":\"Wochentag\",\"selections_count\":\"\",\"selections\":\"\",\"toggle_id\":\"filterbar_day_of_week-toggle-bccdcc5c-a3e7-470b-b6b8-4d26fb48833a\",\"container_id\":\"filterbar_day_of_week-container-bccdcc5c-a3e7-470b-b6b8-4d26fb48833a\",\"pill_toggle_id\":\"filterbar_day_of_week-pill-toggle-bccdcc5c-a3e7-470b-b6b8-4d26fb48833a\",\"is_open\":false,\"name\":\"tribe_dayofweek[]\",\"fields\":[{\"type\":\"checkbox\",\"label\":\"Monday\",\"value\":2,\"id\":\"tribe-events-filterbar-f48be609-monday\",\"name\":\"tribe_dayofweek[]\",\"checked\":false},{\"type\":\"checkbox\",\"label\":\"Tuesday\",\"value\":3,\"id\":\"tribe-events-filterbar-7bb05f67-tuesday\",\"name\":\"tribe_dayofweek[]\",\"checked\":false},{\"type\":\"checkbox\",\"label\":\"Wednesday\",\"value\":4,\"id\":\"tribe-events-filterbar-1c00918e-wednesday\",\"name\":\"tribe_dayofweek[]\",\"checked\":false},{\"type\":\"checkbox\",\"label\":\"Thursday\",\"value\":5,\"id\":\"tribe-events-filterbar-2b5181a8-thursday\",\"name\":\"tribe_dayofweek[]\",\"checked\":false},{\"type\":\"checkbox\",\"label\":\"Friday\",\"value\":6,\"id\":\"tribe-events-filterbar-e54fc0b4-friday\",\"name\":\"tribe_dayofweek[]\",\"checked\":false},{\"type\":\"checkbox\",\"label\":\"Saturday\",\"value\":7,\"id\":\"tribe-events-filterbar-ad332b06-saturday\",\"name\":\"tribe_dayofweek[]\",\"checked\":false},{\"type\":\"checkbox\",\"label\":\"Sunday\",\"value\":1,\"id\":\"tribe-events-filterbar-88f3214b-sunday\",\"name\":\"tribe_dayofweek[]\",\"checked\":false}],\"type\":\"checkbox\"},{\"filter_object\":{\"type\":\"multiselect\",\"name\":\"Stadt\",\"slug\":\"filterbar_city\",\"priority\":6,\"values\":[{\"name\":\"Berlin\",\"value\":\"24169\"},{\"name\":\"Braunschweig\",\"value\":\"12558-14947-15430-19573-22780\"},{\"name\":\"Frankfurt am Main\",\"value\":\"14882\"},{\"name\":\"Garbsen\",\"value\":\"13844-14504\"},{\"name\":\"Hameln\",\"value\":\"19937\"},{\"name\":\"Hannover\",\"value\":\"12369-13016-13058-13813-13819-13874-15317-16229-18424-24404-24408-13257-25894-27541\"},{\"name\":\"K\\u00f6ln\",\"value\":\"19782\"},{\"name\":\"Lingen (Ems)\",\"value\":\"15496-19105-24624\"},{\"name\":\"M\\u00fcnchen\",\"value\":\"16126\"},{\"name\":\"Nordhorn\",\"value\":\"22546-22806-24161\"},{\"name\":\"Vechta\",\"value\":\"19807\"},{\"name\":\"hannover\",\"value\":\"26446\"}],\"free\":null,\"currentValue\":[],\"isActiveFilter\":true,\"queryArgs\":[],\"joinClause\":\"\",\"whereClause\":\"\",\"searched_meta\":\"_VenueCity\",\"relation_meta\":\"_EventVenueID\",\"join_name\":\"city_filter\",\"stack_managed\":false},\"label\":\"Stadt\",\"selections_count\":\"\",\"selections\":\"\",\"toggle_id\":\"filterbar_city-toggle-bccdcc5c-a3e7-470b-b6b8-4d26fb48833a\",\"container_id\":\"filterbar_city-container-bccdcc5c-a3e7-470b-b6b8-4d26fb48833a\",\"pill_toggle_id\":\"filterbar_city-pill-toggle-bccdcc5c-a3e7-470b-b6b8-4d26fb48833a\",\"is_open\":false,\"name\":\"tribe_city[]\",\"fields\":[{\"type\":\"multiselect\",\"value\":\"\",\"id\":\"tribe-events-filterbar-5280f868-filterbar_city\",\"name\":\"tribe_city[]\",\"options\":[{\"text\":\"Berlin\",\"id\":\"24169\",\"value\":\"24169\"},{\"text\":\"Braunschweig\",\"id\":\"12558-14947-15430-19573-22780\",\"value\":\"12558-14947-15430-19573-22780\"},{\"text\":\"Frankfurt am Main\",\"id\":\"14882\",\"value\":\"14882\"},{\"text\":\"Garbsen\",\"id\":\"13844-14504\",\"value\":\"13844-14504\"},{\"text\":\"Hameln\",\"id\":\"19937\",\"value\":\"19937\"},{\"text\":\"Hannover\",\"id\":\"12369-13016-13058-13813-13819-13874-15317-16229-18424-24404-24408-13257-25894-27541\",\"value\":\"12369-13016-13058-13813-13819-13874-15317-16229-18424-24404-24408-13257-25894-27541\"},{\"text\":\"K\\u00f6ln\",\"id\":\"19782\",\"value\":\"19782\"},{\"text\":\"Lingen (Ems)\",\"id\":\"15496-19105-24624\",\"value\":\"15496-19105-24624\"},{\"text\":\"M\\u00fcnchen\",\"id\":\"16126\",\"value\":\"16126\"},{\"text\":\"Nordhorn\",\"id\":\"22546-22806-24161\",\"value\":\"22546-22806-24161\"},{\"text\":\"Vechta\",\"id\":\"19807\",\"value\":\"19807\"},{\"text\":\"hannover\",\"id\":\"26446\",\"value\":\"26446\"}]}],\"type\":\"multiselect\"},{\"filter_object\":{\"type\":\"multiselect\",\"name\":\"Ort\",\"slug\":\"filterbar_venue\",\"priority\":7,\"values\":[{\"name\":\"Agentur f\\u00fcr Arbeit Hannover\",\"value\":15317},{\"name\":\"Courtyard Hotel\",\"value\":13819},{\"name\":\"CyberSicher Zukunftstag\",\"value\":24169},{\"name\":\"Deutsche Messe Technology Academy\",\"value\":13813},{\"name\":\"Dr. Buhmann Schule & Akademie\",\"value\":16229},{\"name\":\"Emsland GmbH, Hasel\\u00fcnner Stra\\u00dfe 3, Meppen, Deutschland\",\"value\":25607},{\"name\":\"Forschungszentrum L3S\",\"value\":18424},{\"name\":\"Glaspalast im Forschungszentrum L3S\",\"value\":13874},{\"name\":\"Handwerkskammer Hannover\",\"value\":24404},{\"name\":\"Hasel\\u00fcnner Stra\\u00dfe 3, 49716 Meppen, Deutschland\",\"value\":24720},{\"name\":\"ICM &#8211; Internationales Congress Center M\\u00fcnchen\",\"value\":16126},{\"name\":\"IFW - Institut f\\u00fcr Fertigungstechnik und Werkzeugmaschinen - Leibniz Universit\\u00e4t Hannover\",\"value\":14504},{\"name\":\"IG Metall\",\"value\":14882},{\"name\":\"IHK Hannover\",\"value\":24408},{\"name\":\"IT-Zentrum Lingen\",\"value\":24624},{\"name\":\"IT-Zentrum Lingen\",\"value\":15496},{\"name\":\"IT-Zentrum Lingen\",\"value\":19105},{\"name\":\"IT-Zentrum Lingen, Kaiserstra\\u00dfe 10B, Lingen (Ems), Deutschland\",\"value\":25617},{\"name\":\"IT-Zentrum Lingen, Kaiserstra\\u00dfe 10B, Lingen (Ems), Deutschland\",\"value\":25695},{\"name\":\"Karriere-Campus Hannover \\u2013 Swiss Life \\u2013 Swiss-Life-Platz 2, 30659 Hannover\",\"value\":25622},{\"name\":\"KOMED im Mediapark\",\"value\":19782},{\"name\":\"K\\u00f6niglicher Pferdestall, Leibniz Universit\\u00e4t Hannover\",\"value\":25894},{\"name\":\"Mittelstand-Digital Zentrum Lingen.M\\u00fcnster.Osnabr\\u00fcck\",\"value\":22806},{\"name\":\"NFF - Nieders\\u00e4chsisches Forschungszentrum Fahrzeugtechnik\",\"value\":22780},{\"name\":\"Niedersachsen.next\",\"value\":27541},{\"name\":\"Nieders\\u00e4chsisches Forschungszentrum f\\u00fcr Fahrzeugtechnik\",\"value\":14947},{\"name\":\"Online\",\"value\":14603},{\"name\":\"Online\",\"value\":27506},{\"name\":\"Online\",\"value\":15068},{\"name\":\"Opernplatz Hannover\",\"value\":12369},{\"name\":\"Schlossplatz Braunschweig\",\"value\":12558},{\"name\":\"Seminarraum Nordhorn\",\"value\":22546},{\"name\":\"Tagungszentrum der Handwerkskammer Hannover\",\"value\":13844},{\"name\":\"Technikhalle Messegel\\u00e4nde\",\"value\":13257},{\"name\":\"Transformationswerk\",\"value\":13016},{\"name\":\"TU Braunschweig, Institut f\\u00fcr Konstruktionstechnik\",\"value\":19573},{\"name\":\"Ulderup Akademie\",\"value\":19807},{\"name\":\"Vechte Arkaden\",\"value\":24161},{\"name\":\"VentureVilla\",\"value\":26446},{\"name\":\"Veranstaltungszentrum \\\"Rotation\\\"\",\"value\":13058},{\"name\":\"Wilhelm5\",\"value\":15430},{\"name\":\"zedita\",\"value\":19937}],\"free\":null,\"currentValue\":[],\"isActiveFilter\":true,\"queryArgs\":[],\"joinClause\":\"\",\"whereClause\":\"\",\"stack_managed\":false},\"label\":\"Ort\",\"selections_count\":\"\",\"selections\":\"\",\"toggle_id\":\"filterbar_venue-toggle-bccdcc5c-a3e7-470b-b6b8-4d26fb48833a\",\"container_id\":\"filterbar_venue-container-bccdcc5c-a3e7-470b-b6b8-4d26fb48833a\",\"pill_toggle_id\":\"filterbar_venue-pill-toggle-bccdcc5c-a3e7-470b-b6b8-4d26fb48833a\",\"is_open\":false,\"name\":\"tribe_venues[]\",\"fields\":[{\"type\":\"multiselect\",\"value\":\"\",\"id\":\"tribe-events-filterbar-d4c1cdcb-filterbar_venue\",\"name\":\"tribe_venues[]\",\"options\":[{\"text\":\"Agentur f\\u00fcr Arbeit Hannover\",\"id\":\"15317\",\"value\":15317},{\"text\":\"Courtyard Hotel\",\"id\":\"13819\",\"value\":13819},{\"text\":\"CyberSicher Zukunftstag\",\"id\":\"24169\",\"value\":24169},{\"text\":\"Deutsche Messe Technology Academy\",\"id\":\"13813\",\"value\":13813},{\"text\":\"Dr. Buhmann Schule & Akademie\",\"id\":\"16229\",\"value\":16229},{\"text\":\"Emsland GmbH, Hasel\\u00fcnner Stra\\u00dfe 3, Meppen, Deutschland\",\"id\":\"25607\",\"value\":25607},{\"text\":\"Forschungszentrum L3S\",\"id\":\"18424\",\"value\":18424},{\"text\":\"Glaspalast im Forschungszentrum L3S\",\"id\":\"13874\",\"value\":13874},{\"text\":\"Handwerkskammer Hannover\",\"id\":\"24404\",\"value\":24404},{\"text\":\"Hasel\\u00fcnner Stra\\u00dfe 3, 49716 Meppen, Deutschland\",\"id\":\"24720\",\"value\":24720},{\"text\":\"ICM &#8211; Internationales Congress Center M\\u00fcnchen\",\"id\":\"16126\",\"value\":16126},{\"text\":\"IFW - Institut f\\u00fcr Fertigungstechnik und Werkzeugmaschinen - Leibniz Universit\\u00e4t Hannover\",\"id\":\"14504\",\"value\":14504},{\"text\":\"IG Metall\",\"id\":\"14882\",\"value\":14882},{\"text\":\"IHK Hannover\",\"id\":\"24408\",\"value\":24408},{\"text\":\"IT-Zentrum Lingen\",\"id\":\"24624\",\"value\":24624},{\"text\":\"IT-Zentrum Lingen\",\"id\":\"15496\",\"value\":15496},{\"text\":\"IT-Zentrum Lingen\",\"id\":\"19105\",\"value\":19105},{\"text\":\"IT-Zentrum Lingen, Kaiserstra\\u00dfe 10B, Lingen (Ems), Deutschland\",\"id\":\"25617\",\"value\":25617},{\"text\":\"IT-Zentrum Lingen, Kaiserstra\\u00dfe 10B, Lingen (Ems), Deutschland\",\"id\":\"25695\",\"value\":25695},{\"text\":\"Karriere-Campus Hannover \\u2013 Swiss Life \\u2013 Swiss-Life-Platz 2, 30659 Hannover\",\"id\":\"25622\",\"value\":25622},{\"text\":\"KOMED im Mediapark\",\"id\":\"19782\",\"value\":19782},{\"text\":\"K\\u00f6niglicher Pferdestall, Leibniz Universit\\u00e4t Hannover\",\"id\":\"25894\",\"value\":25894},{\"text\":\"Mittelstand-Digital Zentrum Lingen.M\\u00fcnster.Osnabr\\u00fcck\",\"id\":\"22806\",\"value\":22806},{\"text\":\"NFF - Nieders\\u00e4chsisches Forschungszentrum Fahrzeugtechnik\",\"id\":\"22780\",\"value\":22780},{\"text\":\"Niedersachsen.next\",\"id\":\"27541\",\"value\":27541},{\"text\":\"Nieders\\u00e4chsisches Forschungszentrum f\\u00fcr Fahrzeugtechnik\",\"id\":\"14947\",\"value\":14947},{\"text\":\"Online\",\"id\":\"14603\",\"value\":14603},{\"text\":\"Online\",\"id\":\"27506\",\"value\":27506},{\"text\":\"Online\",\"id\":\"15068\",\"value\":15068},{\"text\":\"Opernplatz Hannover\",\"id\":\"12369\",\"value\":12369},{\"text\":\"Schlossplatz Braunschweig\",\"id\":\"12558\",\"value\":12558},{\"text\":\"Seminarraum Nordhorn\",\"id\":\"22546\",\"value\":22546},{\"text\":\"Tagungszentrum der Handwerkskammer Hannover\",\"id\":\"13844\",\"value\":13844},{\"text\":\"Technikhalle Messegel\\u00e4nde\",\"id\":\"13257\",\"value\":13257},{\"text\":\"Transformationswerk\",\"id\":\"13016\",\"value\":13016},{\"text\":\"TU Braunschweig, Institut f\\u00fcr Konstruktionstechnik\",\"id\":\"19573\",\"value\":19573},{\"text\":\"Ulderup Akademie\",\"id\":\"19807\",\"value\":19807},{\"text\":\"Vechte Arkaden\",\"id\":\"24161\",\"value\":24161},{\"text\":\"VentureVilla\",\"id\":\"26446\",\"value\":26446},{\"text\":\"Veranstaltungszentrum \\\"Rotation\\\"\",\"id\":\"13058\",\"value\":13058},{\"text\":\"Wilhelm5\",\"id\":\"15430\",\"value\":15430},{\"text\":\"zedita\",\"id\":\"19937\",\"value\":19937}]}],\"type\":\"multiselect\"},{\"filter_object\":{\"type\":\"multiselect\",\"name\":\"Organisator\",\"slug\":\"filterbar_organizer\",\"priority\":9,\"values\":[{\"name\":\"Allianz f\\u00fcr die Region GmbH Team ReTraSON\",\"value\":15431},{\"name\":\"Baugewerbe-Verband Niedersachsen\",\"value\":19929},{\"name\":\"Bechtle IT-Systemhaus Hannover\",\"value\":13278},{\"name\":\"DAISEC\",\"value\":13005},{\"name\":\"Digitalagentur Niedersachsen\",\"value\":22691},{\"name\":\"Digitales Hannover e.V.\",\"value\":12384},{\"name\":\"Handwerkskammer Dortmund Bildungszentrum Hansemann\",\"value\":24557},{\"name\":\"Handwerkskammer Hannover Projekt- und Servicegesellschaft mbH\",\"value\":13847},{\"name\":\"HANNOVER MESSE\",\"value\":18138},{\"name\":\"hwk f\\u00fcr Schwaben\",\"value\":14602},{\"name\":\"IG Metall\",\"value\":14877},{\"name\":\"IHK Schwarzwald-Baar-Heuberg\",\"value\":17486},{\"name\":\"Innovationsnetzwerk Niedersachsen\",\"value\":15155},{\"name\":\"Juliane Tholen, it.emsland\",\"value\":27540},{\"name\":\"kreHtiv Netzwerk Hannover e.V.\",\"value\":13820},{\"name\":\"Mittelstand-Digital Zentren\",\"value\":14876},{\"name\":\"Mittelstand-Digital Zentrum Hannover\",\"value\":20590},{\"name\":\"Mittelstand-Digital Zentrum Lingen.M\\u00fcnser.Osnabr\\u00fcck\",\"value\":25690},{\"name\":\"Mittelstand-Digital Zentrum Lingen.M\\u00fcnster.Osnabr\\u00fcck\",\"value\":20628},{\"name\":\"NachwuchsKraft\",\"value\":12711},{\"name\":\"NBank\",\"value\":24397},{\"name\":\"Nieders\\u00e4chsische Marketinggesellschaft e. V.\",\"value\":13057},{\"name\":\"Nieders\\u00e4chsisches Forschungszentrum Fahrzeugtechnik (NFF)\",\"value\":12564},{\"name\":\"Region Hannover\",\"value\":13009},{\"name\":\"Robokind\",\"value\":15316},{\"name\":\"Stadt Braunschweig\",\"value\":12568},{\"name\":\"Transferstelle Cybersicherheit\",\"value\":21554}],\"free\":null,\"currentValue\":[],\"isActiveFilter\":true,\"queryArgs\":[],\"joinClause\":\"\",\"whereClause\":\"\",\"stack_managed\":false},\"label\":\"Organisator\",\"selections_count\":\"\",\"selections\":\"\",\"toggle_id\":\"filterbar_organizer-toggle-bccdcc5c-a3e7-470b-b6b8-4d26fb48833a\",\"container_id\":\"filterbar_organizer-container-bccdcc5c-a3e7-470b-b6b8-4d26fb48833a\",\"pill_toggle_id\":\"filterbar_organizer-pill-toggle-bccdcc5c-a3e7-470b-b6b8-4d26fb48833a\",\"is_open\":false,\"name\":\"tribe_organizers[]\",\"fields\":[{\"type\":\"multiselect\",\"value\":\"\",\"id\":\"tribe-events-filterbar-d9d812f1-filterbar_organizer\",\"name\":\"tribe_organizers[]\",\"options\":[{\"text\":\"Allianz f\\u00fcr die Region GmbH Team ReTraSON\",\"id\":\"15431\",\"value\":15431},{\"text\":\"Baugewerbe-Verband Niedersachsen\",\"id\":\"19929\",\"value\":19929},{\"text\":\"Bechtle IT-Systemhaus Hannover\",\"id\":\"13278\",\"value\":13278},{\"text\":\"DAISEC\",\"id\":\"13005\",\"value\":13005},{\"text\":\"Digitalagentur Niedersachsen\",\"id\":\"22691\",\"value\":22691},{\"text\":\"Digitales Hannover e.V.\",\"id\":\"12384\",\"value\":12384},{\"text\":\"Handwerkskammer Dortmund Bildungszentrum Hansemann\",\"id\":\"24557\",\"value\":24557},{\"text\":\"Handwerkskammer Hannover Projekt- und Servicegesellschaft mbH\",\"id\":\"13847\",\"value\":13847},{\"text\":\"HANNOVER MESSE\",\"id\":\"18138\",\"value\":18138},{\"text\":\"hwk f\\u00fcr Schwaben\",\"id\":\"14602\",\"value\":14602},{\"text\":\"IG Metall\",\"id\":\"14877\",\"value\":14877},{\"text\":\"IHK Schwarzwald-Baar-Heuberg\",\"id\":\"17486\",\"value\":17486},{\"text\":\"Innovationsnetzwerk Niedersachsen\",\"id\":\"15155\",\"value\":15155},{\"text\":\"Juliane Tholen, it.emsland\",\"id\":\"27540\",\"value\":27540},{\"text\":\"kreHtiv Netzwerk Hannover e.V.\",\"id\":\"13820\",\"value\":13820},{\"text\":\"Mittelstand-Digital Zentren\",\"id\":\"14876\",\"value\":14876},{\"text\":\"Mittelstand-Digital Zentrum Hannover\",\"id\":\"20590\",\"value\":20590},{\"text\":\"Mittelstand-Digital Zentrum Lingen.M\\u00fcnser.Osnabr\\u00fcck\",\"id\":\"25690\",\"value\":25690},{\"text\":\"Mittelstand-Digital Zentrum Lingen.M\\u00fcnster.Osnabr\\u00fcck\",\"id\":\"20628\",\"value\":20628},{\"text\":\"NachwuchsKraft\",\"id\":\"12711\",\"value\":12711},{\"text\":\"NBank\",\"id\":\"24397\",\"value\":24397},{\"text\":\"Nieders\\u00e4chsische Marketinggesellschaft e. V.\",\"id\":\"13057\",\"value\":13057},{\"text\":\"Nieders\\u00e4chsisches Forschungszentrum Fahrzeugtechnik (NFF)\",\"id\":\"12564\",\"value\":12564},{\"text\":\"Region Hannover\",\"id\":\"13009\",\"value\":13009},{\"text\":\"Robokind\",\"id\":\"15316\",\"value\":15316},{\"text\":\"Stadt Braunschweig\",\"id\":\"12568\",\"value\":12568},{\"text\":\"Transferstelle Cybersicherheit\",\"id\":\"21554\",\"value\":21554}]}],\"type\":\"multiselect\"}],\"events\":[10000304,10000286,10000301],\"url\":\"https:\\\/\\\/daisec.de\\\/en\\\/?post_type=tribe_events&eventDisplay=widget-events-list\",\"url_event_date\":false,\"bar\":{\"keyword\":\"\",\"date\":\"\"},\"today\":\"2026-05-13 00:00:00\",\"now\":\"2026-05-13 20:25:47\",\"home_url\":\"https:\\\/\\\/daisec.de\\\/en\",\"rest_url\":\"https:\\\/\\\/daisec.de\\\/en\\\/wp-json\\\/tribe\\\/views\\\/v2\\\/html\",\"rest_method\":\"GET\",\"rest_nonce\":\"\",\"today_url\":\"https:\\\/\\\/daisec.de\\\/en\\\/?post_type=tribe_events&eventDisplay=widget-events-list&rest_route=%2Fwp%2Fv2%2Ftribe_events%2F19309\",\"today_title\":\"Click to select today's date\",\"today_label\":\"Today\",\"prev_label\":\"\",\"next_label\":\"\",\"date_formats\":{\"compact\":\"d.m.Y\",\"month_and_year_compact\":\"m.Y\",\"month_and_year\":\"F Y\",\"time_range_separator\":\" - \",\"date_time_separator\":\"| \"},\"messages\":[],\"start_of_week\":\"1\",\"header_title\":\"\",\"header_title_element\":\"h1\",\"content_title\":\"\",\"show_content_title\":false,\"breadcrumbs\":[],\"backlink\":false,\"before_events\":\"\",\"after_events\":\"\\n<!--\\nThis calendar is powered by The Events Calendar.\\nhttp:\\\/\\\/evnt.is\\\/18wn\\n-->\\n\",\"display_events_bar\":false,\"disable_event_search\":false,\"live_refresh\":true,\"ical\":{\"display_link\":true,\"link\":{\"url\":\"https:\\\/\\\/daisec.de\\\/en\\\/?post_type=tribe_events&#038;eventDisplay=widget-events-list&#038;ical=1\",\"text\":\"Export Events\",\"title\":\"Use this to share calendar data with Google Calendar, Apple iCal and other compatible apps\"}},\"container_classes\":[\"tribe-common\",\"tribe-events\",\"tribe-events-view\",\"tribe-events-view--widget-events-list\",\"tribe-events-widget\"],\"container_data\":[],\"is_past\":false,\"breakpoints\":{\"xsmall\":500,\"medium\":768,\"full\":960},\"breakpoint_pointer\":\"bccdcc5c-a3e7-470b-b6b8-4d26fb48833a\",\"is_initial_load\":false,\"public_views\":{\"list\":{\"view_class\":\"Tribe\\\\Events\\\\Views\\\\V2\\\\Views\\\\List_View\",\"view_url\":\"https:\\\/\\\/daisec.de\\\/en\\\/events\\\/(\\\/?:list|liste)\\\/\",\"view_label\":\"List\",\"aria_label\":\"Display Events in List View\"},\"month\":{\"view_class\":\"Tribe\\\\Events\\\\Views\\\\V2\\\\Views\\\\Month_View\",\"view_url\":\"https:\\\/\\\/daisec.de\\\/en\\\/events\\\/(\\\/?:month|monat)\\\/\",\"view_label\":\"Month\",\"aria_label\":\"Display Events in Month View\"},\"day\":{\"view_class\":\"Tribe\\\\Events\\\\Views\\\\V2\\\\Views\\\\Day_View\",\"view_url\":\"https:\\\/\\\/daisec.de\\\/en\\\/events\\\/(\\\/?:today|heute)\\\/\",\"view_label\":\"Day\",\"aria_label\":\"Display Events in Day View\"}},\"show_latest_past\":false,\"past\":false,\"compatibility_classes\":[\"tribe-compatibility-container\"],\"view_more_text\":\"View Calendar\",\"view_more_title\":\"View more events.\",\"view_more_link\":\"https:\\\/\\\/daisec.de\\\/en\\\/events\\\/\",\"widget_title\":\"Kommende Veranstaltungen\",\"hide_if_no_upcoming_events\":true,\"display\":{\"cost\":false,\"venue\":false,\"street\":false,\"city\":false,\"region\":false,\"zip\":false,\"country\":false,\"phone\":false,\"organizer\":false,\"website\":false},\"subscribe_links\":{\"gcal\":{\"label\":\"Google Calendar\",\"single_label\":\"Add to Google Calendar\",\"visible\":true,\"block_slug\":\"hasGoogleCalendar\"},\"ical\":{\"label\":\"iCalendar\",\"single_label\":\"Add to iCalendar\",\"visible\":true,\"block_slug\":\"hasiCal\"},\"outlook-365\":{\"label\":\"Outlook 365\",\"single_label\":\"Outlook 365\",\"visible\":true,\"block_slug\":\"hasOutlook365\"},\"outlook-live\":{\"label\":\"Outlook Live\",\"single_label\":\"Outlook Live\",\"visible\":true,\"block_slug\":\"hasOutlookLive\"},\"ics\":{\"label\":\"Export .ics file\",\"single_label\":\"Export .ics file\",\"visible\":true,\"block_slug\":null},\"outlook-ics\":{\"label\":\"Export Outlook .ics file\",\"single_label\":\"Export Outlook .ics file\",\"visible\":true,\"block_slug\":null}},\"layout\":\"vertical\",\"filterbar_state\":\"open\",\"selected_filters\":[],\"mobile_initial_state_control\":true,\"display_recurring_toggle\":false,\"_context\":{\"slug\":\"widget-events-list\"}}<\/script>\n\n\t\t\t\t\t\t\t<header class=\"tribe-events-widget-events-list__header\">\n\t\t\t\t\t<h2 class=\"tribe-events-widget-events-list__header-title tribe-common-h6 tribe-common-h--alt\">\n\t\t\t\t\t\tKommende Veranstaltungen\t\t\t\t\t<\/h2>\n\t\t\t\t<\/header>\n\t\t\t\n\t\t\t\n\t\t\t\t<div class=\"tribe-events-widget-events-list__events\">\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-05-28\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tMay\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t28\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10000304 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tribe_events_cat-webinar cat_workshops\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-05-28\">\n\t\t<span class=\"tribe-event-date-start\">14:00<\/span> &#8211; <span class=\"tribe-event-time\">17:00<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a href=\"https:\/\/digitalzentrum-lmo.de\/veranstaltung\/cloud-abhaengigkeiten-alternativen\/\" title=\"Cloudbetrieb und alternative Modelle: Abh\u00e4ngigkeiten erkennen \u2013 Alternativen gestalten\" rel=\"bookmark noopener\" class=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\" target=\"_blank\">\n\t\tCloudbetrieb und alternative Modelle: Abh\u00e4ngigkeiten erkennen \u2013 Alternativen gestalten\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-06-04\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tJun\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t4\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10000286 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tag-cybersicherheit tag-ki tag-schulung tribe_events_cat-digitalisierungsmanager tribe_events_cat-qualifizierungsprogramm cat_workshops\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-06-04\">\n\t\t<span class=\"tribe-event-date-start\">10:00<\/span> &#8211; <span class=\"tribe-event-time\">15:00<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a href=\"https:\/\/daisec.de\/en\/event\/qualifizierungsprogramm-digitalisierungsmanager-ki-cybersicherheit-06-2026\/\" title=\"Qualifizierungsprogramm Digitalisierungsmanager: KI &amp; Cybersicherheit\" rel=\"bookmark\" class=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\">\n\t\tQualifizierungsprogramm Digitalisierungsmanager: KI &amp; Cybersicherheit\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div  class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\" >\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-06-16\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tJun\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t16\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article  class=\"tribe-events-widget-events-list__event post-10000301 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tag-innovation tag-ki tag-kmu tag-kultur tag-strategie tag-wirtschaft tag-wissenschaft tag-workshop cat_workshops\" >\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-06-16\">\n\t\t<span class=\"tribe-event-date-start\">10:00<\/span> &#8211; <span class=\"tribe-event-time\">15:30<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a href=\"https:\/\/innomatch.nds.de\/events\/default\/innovationskraft-im-netzwerk-von-der-vision-zum-konkreten-handlungsplan\/zw2dJGpr0M\" title=\"Innovationskraft im Netzwerk: Von der Vision zum konkreten Handlungsplan\" rel=\"bookmark noopener\" class=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\" target=\"_blank\">\n\t\tInnovationskraft im Netzwerk: Von der Vision zum konkreten Handlungsplan\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"tribe-events-widget-events-list__view-more tribe-common-b1 tribe-common-b2--min-medium\">\n\t<a href=\"https:\/\/daisec.de\/en\/events\/\" class=\"tribe-events-widget-events-list__view-more-link tribe-common-anchor-thin\" title=\"View more events.\">\n\t\tView Calendar\t<\/a>\n<\/div>\n\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<script data-js='tribe-events-view-nonce-data' type='application\/json'>{\"tvn1\":\"067815bdd1\",\"tvn2\":\"\"}<\/script>\n","protected":false},"excerpt":{"rendered":"<p>K\u00fcnstliche Intelligenz entwickelt sich rasant und ist aus unserem Alltag nicht mehr wegzudenken. Dieser Workshop bietet einen theoretischen und praktischen Einstieg in das Thema. In einem intensiven Theoriemodul werden zun\u00e4chst die Grundlagen der K\u00fcnstlichen Intelligenz und des Deep Learning vermittelt. Das erworbene Wissen kann anschlie\u00dfend bei der Programmierung erster KI-Anwendungen angewendet werden.<\/p>","protected":false},"author":6,"featured_media":19311,"template":"","meta":{"_tec_requires_first_save":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_EventAllDay":false,"_EventTimezone":"Europe\/Berlin","_EventStartDate":"2024-06-07 09:15:00","_EventEndDate":"2024-06-07 15:00:00","_EventStartDateUTC":"2024-06-07 07:15:00","_EventEndDateUTC":"2024-06-07 13:00:00","_EventShowMap":false,"_EventShowMapLink":true,"_EventURL":"","_EventCost":"Free","_EventCostDescription":"","_EventCurrencySymbol":"\u20ac","_EventCurrencyCode":"EUR","_EventCurrencyPosition":"prefix","_EventDateTimeSeparator":"| ","_EventTimeRangeSeparator":" - ","_EventOrganizerID":[],"_EventVenueID":[14947],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_blocks_recurrence_rules":"","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"","_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[36,87,48,38],"tribe_events_cat":[33],"class_list":["post-19309","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-ki","tag-praxis-workshop","tag-programmieren","tag-schulung","tribe_events_cat-workshops","cat_workshops"],"ticketed":["rsvp"],"_links":{"self":[{"href":"https:\/\/daisec.de\/en\/wp-json\/wp\/v2\/tribe_events\/19309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/daisec.de\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/daisec.de\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/daisec.de\/en\/wp-json\/wp\/v2\/users\/6"}],"version-history":[{"count":0,"href":"https:\/\/daisec.de\/en\/wp-json\/wp\/v2\/tribe_events\/19309\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/daisec.de\/en\/wp-json\/wp\/v2\/media\/19311"}],"wp:attachment":[{"href":"https:\/\/daisec.de\/en\/wp-json\/wp\/v2\/media?parent=19309"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/daisec.de\/en\/wp-json\/wp\/v2\/tags?post=19309"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/daisec.de\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=19309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}